{"id":2291,"date":"2020-07-28T09:27:23","date_gmt":"2020-07-28T09:27:23","guid":{"rendered":"https:\/\/von-direkt-vor-der-tuer.de\/?p=2291"},"modified":"2020-07-28T10:55:38","modified_gmt":"2020-07-28T10:55:38","slug":"ein-zwei-mehrweg","status":"publish","type":"post","link":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/2020\/07\/28\/ein-zwei-mehrweg\/","title":{"rendered":"Ein-, Zwei-, Mehrweg"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2291\" class=\"elementor elementor-2291\">\n\t\t\t\t\t\t<section data-angle=\"57deg\" data-color=\"#A9CA2B,#99CEF1,#D296C2,#ED8700,#FEEA50\" class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-c2e79ac elementor-section-content-middle elementor-section-stretched elementor-section-height-min-height eae-animated-gradient-yes elementor-section-boxed elementor-section-height-default elementor-section-items-middle\" data-eae-slider=\"90217\" data-id=\"c2e79ac\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;slideshow&quot;,&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_slideshow_gallery&quot;:[],&quot;background_slideshow_loop&quot;:&quot;yes&quot;,&quot;background_slideshow_slide_duration&quot;:5000,&quot;background_slideshow_slide_transition&quot;:&quot;fade&quot;,&quot;background_slideshow_transition_duration&quot;:500}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-cb55b3e\" data-eae-slider=\"75856\" data-id=\"cb55b3e\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bacbe6 elementor-widget elementor-widget-image\" data-id=\"2bacbe6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"597\" src=\"https:\/\/www.von-direkt-vor-der-tuer.de\/wp-content\/uploads\/2020\/07\/Salvus_Kiste_Imageaufnahme_Spiegelung-768x597.jpg\" class=\"attachment-medium_large size-medium_large wp-image-2298\" alt=\"\" srcset=\"https:\/\/www.von-direkt-vor-der-tuer.de\/wp-content\/uploads\/2020\/07\/Salvus_Kiste_Imageaufnahme_Spiegelung-768x597.jpg 768w, https:\/\/www.von-direkt-vor-der-tuer.de\/wp-content\/uploads\/2020\/07\/Salvus_Kiste_Imageaufnahme_Spiegelung-300x233.jpg 300w, https:\/\/www.von-direkt-vor-der-tuer.de\/wp-content\/uploads\/2020\/07\/Salvus_Kiste_Imageaufnahme_Spiegelung.jpg 900w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-1349a25 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"52732\" data-id=\"1349a25\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d288c24\" data-eae-slider=\"89558\" data-id=\"d288c24\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e8edfac elementor-widget elementor-widget-spacer\" data-id=\"e8edfac\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-79320679 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"83127\" data-id=\"79320679\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-4f4f6aa1\" data-eae-slider=\"16535\" data-id=\"4f4f6aa1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-acfb3cc elementor-widget elementor-widget-heading\" data-id=\"acfb3cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Einweg - Zweiweg - Mehrweg - was bedeutet das?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26570140 elementor-widget elementor-widget-text-editor\" data-id=\"26570140\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\">Lassen Sie sich die beiden W\u00f6rter &#8222;Einweg&#8220; und &#8222;Mehrweg&#8220; einmal in Ruhe auf der Zunge zergehen. Gemerkt? Der Unterschied zwischen beiden Verpackungen steckt bereits im Namen: Die Einwegflasche bekommt nur eine Chance, die Mehrwegflasche wird dagegen mehrfach bef\u00fcllt.<br \/><br \/>Mehrwegflaschen, egal ob aus Kunststoff oder Glas, sind langlebig. Glas-Mehrwegflaschen k\u00f6nnen z.B. bis zu 50 Mal wieder bef\u00fcllt werden und haben somit eine Lebensdauer von fast sieben Jahren. Die Kunststoffflaschen werden bis zu 25 Mal mit Getr\u00e4nken bef\u00fcllt.<br \/><br \/>Dank der h\u00e4ufigen Wiederverwertung ist der Co<sub>2<\/sub>-Fu\u00dfabdruck von Mehrwegflaschen gering und das schont die Umwelt. In diese Berechnung flie\u00dfen alle Faktoren mit ein: Die Rohstoffgewinnung, die Produktion der Flaschen, die Transportwege und das Sp\u00fclen und Reinigen der Mehrwegflaschen.<br \/>Das Pfand f\u00fcr Mehrwegflaschen, egal ob aus Glas oder PET, betr\u00e4gt 15 Cent. F\u00fcr Bier-Mehrwegflaschen bekommt man bei der Abgabe 8 Cent zur\u00fcck.<br \/><br \/>Auch Einwegflaschen werden wiederverwertet bzw. recycelt und z.B. zu neuen Flaschen verarbeitet. Das Pfand f\u00fcr die Einwegflaschen liegt einheitlich bei 25 Cent.<br \/>Einwegverpackungen mit Pfand erkennt man in Deutschland immer an dem Logo der DPG (Flasche und Dose von einem Pfeil unterstrichen).<\/p>\n<p>\u00a0<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-69c171b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"87266\" data-id=\"69c171b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7d6a993\" data-eae-slider=\"26333\" data-id=\"7d6a993\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-27b0a89 elementor-widget elementor-widget-spacer\" data-id=\"27b0a89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"has_eae_slider elementor-section elementor-top-section elementor-element elementor-element-5c0f36f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-eae-slider=\"62755\" data-id=\"5c0f36f\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"has_eae_slider elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e509990\" data-eae-slider=\"24853\" data-id=\"e509990\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0475919 animation-style_1 elementor-widget elementor-widget-eae-dual-button\" data-id=\"0475919\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"eae-dual-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"eae-dual-button-main-wrapper\">\n\t\t\t<div class=\"eae-dual-button-wrapper button-style-horizontal\">\n\t\t\t\t<div class=\"eae-button1\">\n\t\t\t\t\t<a class=\"eae-button-1-wrapper eae-sweep-left\" href=\"https:\/\/von-direkt-vor-der-tuer.de\/\">\n\t\t\t\t\t\t<div class=\"eae-button-1 icon-after\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-db-icon-wrapper\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-left\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-button-text\">Zur\u00fcck zur Startseite<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"eae-button-separator-wrapper\">\n\t\t\t\t\t\t\t<span class=\"eae-button-separator\">\n\t\t\t\t\t\t\t\t<span>\n\t\t\t\t\t\t\t\t\toder\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"eae-button2\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"eae-button-2-wrapper eae-sweep-right\" href=\"https:\/\/von-direkt-vor-der-tuer.de\/index.php\/wassermachtahh\/\">\n\t\t\t\t\t\t<div class=\"eae-button-2 icon-after\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-db-icon-wrapper\">\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-arrow-alt-circle-left\"><\/i>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"eae-button-text\">Zur\u00fcck zur \u00dcbersicht<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-24d9431 elementor-widget elementor-widget-spacer\" data-id=\"24d9431\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Einweg &#8211; Zweiweg &#8211; Mehrweg &#8211; was bedeutet das? Lassen Sie sich die beiden W\u00f6rter &#8222;Einweg&#8220; und &#8222;Mehrweg&#8220; einmal in Ruhe auf der Zunge zergehen. Gemerkt? Der Unterschied zwischen beiden Verpackungen steckt bereits im Namen: Die Einwegflasche bekommt nur eine Chance, die Mehrwegflasche wird dagegen mehrfach bef\u00fcllt. Mehrwegflaschen, egal ob aus Kunststoff oder Glas, sind [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":2298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[28],"tags":[],"class_list":["post-2291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-wassermachtahh"],"_links":{"self":[{"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/posts\/2291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/comments?post=2291"}],"version-history":[{"count":4,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/posts\/2291\/revisions"}],"predecessor-version":[{"id":2324,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/posts\/2291\/revisions\/2324"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/media\/2298"}],"wp:attachment":[{"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/media?parent=2291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/categories?post=2291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.von-direkt-vor-der-tuer.de\/index.php\/wp-json\/wp\/v2\/tags?post=2291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}